{"id":12661,"date":"2026-05-06T15:34:26","date_gmt":"2026-05-06T13:34:26","guid":{"rendered":"https:\/\/www.ecolenormalecortot.com\/?post_type=teacher&#038;p=12661"},"modified":"2026-05-06T16:32:50","modified_gmt":"2026-05-06T14:32:50","slug":"vincent-courtois","status":"publish","type":"teacher","link":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/","title":{"rendered":"Vincent COURTOIS"},"content":{"rendered":"\n<p>A former student of the ENMP (Ecole Normale de Musique de Paris) in Genevi\u00e8ve Teuli\u00e8res&#8217; class, Vincent Courtois retains from his classical training the technique, precision, and mastery of the instrument. He also studied with Xavier Gagnepain, Roland Pidoux, and Fr\u00e9d\u00e9ric Lod\u00e9on. His curiosity and eclecticism led him early on to play in various ensembles of musicians with very different styles, from Rita Mitsouko to Christian Escoud\u00e9, including Michel Petrucciani and Michel Portal. With Sylvie Courvoisier, Dominique Pifar\u00e9ly, Jo\u00eblle L\u00e9andre, and Joachim K\u00fchn, he rediscovered the classical aspect of his instrument. His participation in Rabih Abou Kahlil&#8217;s ensembles liberated him as a soloist. His encounter with Louis Sclavis, with whom he shares a cinematic approach to music, revealed in him a keen sense of melody.<\/p>\n\n\n\n<p>Drawing on his diverse experiences, Vincent Courtois has developed a unique musical style. The foundation of his creative process is a play of correspondences, a delicate balance of personalities and energies, an effect of contrast, and ideas of sound, image, uncertainty, and silence. Thus creating music where freedom is paradoxically managed with absolute rigor, attentive to the smallest detail, he gives the collective a chance and each individual a place. For over fifteen years, Vincent Courtois has led a now-essential trio with saxophonists Robin Fincker and Daniel Erdmann. Through the Compagnie de l\u2019Impr\u00e9vu, he founded the Cello Workshops in 2021 with No\u00e9mi Boutin and Eric-Maria Couturier, and since 2024 has taught improvisation at the CNSM in Lyon.<\/p>\n\n\n\n<p>Vincent Courtois is a Chevalier de l\u2019Ordre des Arts et des Lettres.<\/p>\n","protected":false},"featured_media":12660,"template":"","discipline":[132,191,187],"class_list":["post-12661","teacher","type-teacher","status-publish","has-post-thumbnail","hentry","discipline-cello","discipline-cello-jazz","discipline-jazz-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vincent COURTOIS - Ecole Normale de Musique de Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vincent COURTOIS - Ecole Normale de Musique de Paris\" \/>\n<meta property=\"og:description\" content=\"A former student of the ENMP (Ecole Normale de Musique de Paris) in Genevi\u00e8ve Teuli\u00e8res&#8217; class, Vincent Courtois retains from [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecole Normale de Musique de Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T14:32:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2026\/05\/JBM4991_2-\u00a9Jean-Baptiste-Millot--scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/vincent-courtois\\\/\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/vincent-courtois\\\/\",\"name\":\"Vincent COURTOIS - Ecole Normale de Musique de Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/vincent-courtois\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/vincent-courtois\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/JBM4991_2-\u00a9Jean-Baptiste-Millot--scaled.jpeg\",\"datePublished\":\"2026-05-06T13:34:26+00:00\",\"dateModified\":\"2026-05-06T14:32:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/vincent-courtois\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/vincent-courtois\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/vincent-courtois\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/JBM4991_2-\u00a9Jean-Baptiste-Millot--scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/JBM4991_2-\u00a9Jean-Baptiste-Millot--scaled.jpeg\",\"width\":2560,\"height\":1703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/vincent-courtois\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professeurs\",\"item\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/enseignants\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vincent COURTOIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/\",\"name\":\"Ecole Normale de Musique de Paris\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#organization\",\"name\":\"Ecole Normale de Musique de Paris\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/android-chrome-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/android-chrome-512x512-1.png\",\"width\":512,\"height\":512,\"caption\":\"Ecole Normale de Musique de Paris\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vincent COURTOIS - Ecole Normale de Musique de Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/","og_locale":"en_US","og_type":"article","og_title":"Vincent COURTOIS - Ecole Normale de Musique de Paris","og_description":"A former student of the ENMP (Ecole Normale de Musique de Paris) in Genevi\u00e8ve Teuli\u00e8res&#8217; class, Vincent Courtois retains from [&hellip;]","og_url":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/","og_site_name":"Ecole Normale de Musique de Paris","article_modified_time":"2026-05-06T14:32:50+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2026\/05\/JBM4991_2-\u00a9Jean-Baptiste-Millot--scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/","url":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/","name":"Vincent COURTOIS - Ecole Normale de Musique de Paris","isPartOf":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/#primaryimage"},"image":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2026\/05\/JBM4991_2-\u00a9Jean-Baptiste-Millot--scaled.jpeg","datePublished":"2026-05-06T13:34:26+00:00","dateModified":"2026-05-06T14:32:50+00:00","breadcrumb":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/#primaryimage","url":"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2026\/05\/JBM4991_2-\u00a9Jean-Baptiste-Millot--scaled.jpeg","contentUrl":"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2026\/05\/JBM4991_2-\u00a9Jean-Baptiste-Millot--scaled.jpeg","width":2560,"height":1703},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/vincent-courtois\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ecolenormalecortot.com\/en\/"},{"@type":"ListItem","position":2,"name":"Professeurs","item":"https:\/\/www.ecolenormalecortot.com\/en\/enseignants\/"},{"@type":"ListItem","position":3,"name":"Vincent COURTOIS"}]},{"@type":"WebSite","@id":"https:\/\/www.ecolenormalecortot.com\/en\/#website","url":"https:\/\/www.ecolenormalecortot.com\/en\/","name":"Ecole Normale de Musique de Paris","description":"","publisher":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecolenormalecortot.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ecolenormalecortot.com\/en\/#organization","name":"Ecole Normale de Musique de Paris","url":"https:\/\/www.ecolenormalecortot.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ecolenormalecortot.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2023\/02\/android-chrome-512x512-1.png","contentUrl":"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2023\/02\/android-chrome-512x512-1.png","width":512,"height":512,"caption":"Ecole Normale de Musique de Paris"},"image":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/teacher\/12661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/teacher"}],"about":[{"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/types\/teacher"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/media\/12660"}],"wp:attachment":[{"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/media?parent=12661"}],"wp:term":[{"taxonomy":"discipline","embeddable":true,"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/discipline?post=12661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}