{"id":171,"count":3,"description":"","link":"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/","name":"Ateliers","slug":"ateliers","taxonomy":"discipline","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Ateliers - Ecole Normale de Musique de Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Ateliers - Ecole Normale de Musique de Paris\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecole Normale de Musique de Paris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/discipline\\\/ateliers\\\/\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/discipline\\\/ateliers\\\/\",\"name\":\"Archives des Ateliers - Ecole Normale de Musique de Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/discipline\\\/ateliers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/discipline\\\/ateliers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ateliers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/\",\"name\":\"Ecole Normale de Musique de Paris\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#organization\",\"name\":\"Ecole Normale de Musique de Paris\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/android-chrome-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/android-chrome-512x512-1.png\",\"width\":512,\"height\":512,\"caption\":\"Ecole Normale de Musique de Paris\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ecolenormalecortot.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Ateliers - Ecole Normale de Musique de Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Ateliers - Ecole Normale de Musique de Paris","og_url":"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/","og_site_name":"Ecole Normale de Musique de Paris","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/","url":"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/","name":"Archives des Ateliers - Ecole Normale de Musique de Paris","isPartOf":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecolenormalecortot.com\/en\/discipline\/ateliers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ecolenormalecortot.com\/en\/"},{"@type":"ListItem","position":2,"name":"Ateliers"}]},{"@type":"WebSite","@id":"https:\/\/www.ecolenormalecortot.com\/en\/#website","url":"https:\/\/www.ecolenormalecortot.com\/en\/","name":"Ecole Normale de Musique de Paris","description":"","publisher":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecolenormalecortot.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ecolenormalecortot.com\/en\/#organization","name":"Ecole Normale de Musique de Paris","url":"https:\/\/www.ecolenormalecortot.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ecolenormalecortot.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2023\/02\/android-chrome-512x512-1.png","contentUrl":"https:\/\/www.ecolenormalecortot.com\/wp-content\/uploads\/2023\/02\/android-chrome-512x512-1.png","width":512,"height":512,"caption":"Ecole Normale de Musique de Paris"},"image":{"@id":"https:\/\/www.ecolenormalecortot.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/discipline\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/discipline"}],"about":[{"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/taxonomies\/discipline"}],"wp:post_type":[{"href":"https:\/\/www.ecolenormalecortot.com\/en\/wp-json\/wp\/v2\/teacher?discipline=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}